{"id":18624,"date":"2026-07-18T16:42:00","date_gmt":"2026-07-18T13:42:00","guid":{"rendered":"https:\/\/physiomed.store\/uncategorized\/%ce%bf%ce%bc%cf%86%ce%b1%ce%bb%ce%bf%ce%b5%cf%80%ce%b9%ce%b4%ce%b5%cf%83%ce%bc%ce%bf%cf%82-%ce%bc%ce%bf%ce%b2%ce%b9%ce%b1%ce%ba\/"},"modified":"2026-07-18T16:42:04","modified_gmt":"2026-07-18T13:42:04","slug":"%ce%bf%ce%bc%cf%86%ce%b1%ce%bb%ce%bf%ce%b5%cf%80%ce%b9%ce%b4%ce%b5%cf%83%ce%bc%ce%bf%cf%82-%ce%bc%ce%bf%ce%b2%ce%b9%ce%b1%ce%ba","status":"publish","type":"product","link":"https:\/\/physiomed.store\/en\/\u03bf\u03c1\u03b8\u03bf\u03c0\u03b5\u03b4\u03b9\u03ba\u03ac\/\u03ba\u03bf\u03c1\u03bc\u03cc\u03c2\/%ce%bf%ce%bc%cf%86%ce%b1%ce%bb%ce%bf%ce%b5%cf%80%ce%b9%ce%b4%ce%b5%cf%83%ce%bc%ce%bf%cf%82-%ce%bc%ce%bf%ce%b2%ce%b9%ce%b1%ce%ba\/","title":{"rendered":"\u039f\u039c\u03a6\u0391\u039b\u039f\u0395\u03a0\u0399\u0394\u0395\u03a3\u039c\u039f\u03a3 \u039c\u039f\u0392\u0399\u0391\u039a"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>\u039f\u039c\u03a6\u0391\u039b\u039f\u0395\u03a0\u0399\u0394\u0395\u03a3\u039c\u039f\u03a3 \u039c\u039f\u0392\u0399\u0391\u039a<\/p>","protected":false},"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":""},"product_brand":[],"product_cat":[4458,16],"product_tag":[],"class_list":["post-18624","product","type-product","status-publish","product_cat-4458","product_cat-16","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"trp-custom-language-flag":false,"woocommerce_thumbnail":false,"woocommerce_single":false,"woocommerce_gallery_thumbnail":false,"dgwt-wcas-product-suggestion":false},"uagb_author_info":{"display_name":"PhysioMED","author_link":"https:\/\/physiomed.store\/en\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"\u039f\u039c\u03a6\u0391\u039b\u039f\u0395\u03a0\u0399\u0394\u0395\u03a3\u039c\u039f\u03a3 \u039c\u039f\u0392\u0399\u0391\u039a","_links":{"self":[{"href":"https:\/\/physiomed.store\/en\/wp-json\/wp\/v2\/product\/18624","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/physiomed.store\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/physiomed.store\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/physiomed.store\/en\/wp-json\/wp\/v2\/comments?post=18624"}],"wp:attachment":[{"href":"https:\/\/physiomed.store\/en\/wp-json\/wp\/v2\/media?parent=18624"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/physiomed.store\/en\/wp-json\/wp\/v2\/product_brand?post=18624"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/physiomed.store\/en\/wp-json\/wp\/v2\/product_cat?post=18624"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/physiomed.store\/en\/wp-json\/wp\/v2\/product_tag?post=18624"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}